{"id":8642,"date":"2026-05-13T09:41:15","date_gmt":"2026-05-13T07:41:15","guid":{"rendered":"https:\/\/golf-entreprise-ara.org\/wpara\/?p=8642"},"modified":"2026-05-13T09:41:15","modified_gmt":"2026-05-13T07:41:15","slug":"latscaf-63-ouvre-le-golf-a-toutes-ses-sections","status":"publish","type":"post","link":"https:\/\/golf-entreprise-ara.org\/wpara\/latscaf-63-ouvre-le-golf-a-toutes-ses-sections\/","title":{"rendered":"L&rsquo;ATSCAF 63 ouvre le golf \u00e0 toutes ses sections"},"content":{"rendered":"<p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\"><strong>Golf d&rsquo;Entreprise \u00b7 Initiation | Samedi 25 avril 2026 | Golf de Royat Charade \u00b7 Clermont-Ferrand (63)<\/strong><\/p>\n<hr class=\"border-border-200 border-t-0.5 my-3 mx-1.5\" \/>\n<p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\">La section golf de l&rsquo;<strong>ATSCAF 63<\/strong> avait eu l&rsquo;id\u00e9e originale d&rsquo;inviter des membres de toutes les sections de l&rsquo;association \u00e0 venir d\u00e9couvrir le golf ce samedi 25 avril au matin. Un pari r\u00e9ussi : onze membres venus d&rsquo;horizons tr\u00e8s divers ont r\u00e9pondu \u00e0 l&rsquo;appel et rejoint le <strong>Golf de Royat Charade<\/strong> pour deux heures d&rsquo;initiation.<\/p>\n<p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\">Piscine, aquagym, tarot, \u0153nologie, badminton, randonn\u00e9e, g\u00e9n\u00e9alogie \u2014 sept sections repr\u00e9sent\u00e9es, une m\u00eame curiosit\u00e9 pour ce sport qu&rsquo;ils n&rsquo;avaient pour la plupart jamais pratiqu\u00e9.<\/p>\n<h2 class=\"text-text-100 mt-3 -mb-1 text-[1.125rem] font-bold\">Une matin\u00e9e bien organis\u00e9e<\/h2>\n<p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\">L&rsquo;accueil a \u00e9t\u00e9 assur\u00e9 par <strong>Philippe Lequeu<\/strong>, pr\u00e9sident de la commission sportive du Golf de Royat Charade et responsable comp\u00e9tition de la section golf de l&rsquo;ATSCAF 63. Les onze membres \u00e9taient accompagn\u00e9s de quelques adh\u00e9rents de la section golf et de la responsable de celle-ci, <strong>Nicole Audebert-Pichon<\/strong>, pour une initiation de deux heures anim\u00e9e par le professionnel du club, <strong>Serge Paulhan<\/strong>.<\/p>\n<p><strong><img loading=\"lazy\" decoding=\"async\" class=\"alignnone  wp-image-8644\" src=\"https:\/\/golf-entreprise-ara.org\/wpara\/wp-content\/uploads\/IMG20260425114734-300x225.jpg\" alt=\"\" width=\"400\" height=\"300\" srcset=\"https:\/\/golf-entreprise-ara.org\/wpara\/wp-content\/uploads\/IMG20260425114734-300x225.jpg 300w, https:\/\/golf-entreprise-ara.org\/wpara\/wp-content\/uploads\/IMG20260425114734-1024x768.jpg 1024w, https:\/\/golf-entreprise-ara.org\/wpara\/wp-content\/uploads\/IMG20260425114734-768x576.jpg 768w, https:\/\/golf-entreprise-ara.org\/wpara\/wp-content\/uploads\/IMG20260425114734-1536x1152.jpg 1536w, https:\/\/golf-entreprise-ara.org\/wpara\/wp-content\/uploads\/IMG20260425114734-2048x1536.jpg 2048w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/strong><\/p>\n<h2 class=\"text-text-100 mt-3 -mb-1 text-[1.125rem] font-bold\">Deux heures pour d\u00e9couvrir les fondamentaux<\/h2>\n<p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\">La s\u00e9ance s&rsquo;est articul\u00e9e autour de quatre temps forts :<\/p>\n<p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\"><strong>Putting sur les greens<\/strong><\/p>\n<p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\">Premiers contacts avec le putter pour apprivoiser le geste court et comprendre que la pr\u00e9cision vers le petit trou ne s&rsquo;improvise pas. Une r\u00e9v\u00e9lation pour beaucoup !<\/p>\n<p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\"><strong>Geste de base au practice<\/strong><\/p>\n<p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\">Maniement du club, posture, premiers swings \u2014 Serge Paulhan a transmis avec p\u00e9dagogie les bases indispensables pour aborder le golf dans les meilleures conditions.<\/p>\n<p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\"><strong>Exercice sur le parcours 3 trous d&rsquo;entra\u00eenement<\/strong><\/p>\n<p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\">Pour conclure la partie technique, un passage sur le petit parcours d&rsquo;entra\u00eenement 3 trous \u2014 et la d\u00e9couverte du vrai golf, avec ses surprises, ses exigences et ses joies.<\/p>\n<p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\"><strong>Pot de l&rsquo;amiti\u00e9 &amp; cadeaux du golf<\/strong><\/p>\n<p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\">Apr\u00e8s l&rsquo;effort, le r\u00e9confort ! Le golf a offert un pot de l&rsquo;amiti\u00e9 bien m\u00e9rit\u00e9, un bon pour le pr\u00eat de mat\u00e9riel et deux jetons de practice \u2014 pour encourager les plus motiv\u00e9s \u00e0 revenir d\u00e8s que possible.<\/p>\n<p>\u00a0<img loading=\"lazy\" decoding=\"async\" class=\"alignnone  wp-image-8646\" src=\"https:\/\/golf-entreprise-ara.org\/wpara\/wp-content\/uploads\/IMG20260425122801-300x225.jpg\" alt=\"\" width=\"400\" height=\"300\" srcset=\"https:\/\/golf-entreprise-ara.org\/wpara\/wp-content\/uploads\/IMG20260425122801-300x225.jpg 300w, https:\/\/golf-entreprise-ara.org\/wpara\/wp-content\/uploads\/IMG20260425122801-1024x768.jpg 1024w, https:\/\/golf-entreprise-ara.org\/wpara\/wp-content\/uploads\/IMG20260425122801-768x576.jpg 768w, https:\/\/golf-entreprise-ara.org\/wpara\/wp-content\/uploads\/IMG20260425122801-1536x1152.jpg 1536w, https:\/\/golf-entreprise-ara.org\/wpara\/wp-content\/uploads\/IMG20260425122801.jpg 2048w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/p>\n<h2 class=\"text-text-100 mt-3 -mb-1 text-[1.125rem] font-bold\">La parole \u00e0 un participant<\/h2>\n<blockquote class=\"ml-2 border-l-4 border-border-300\/10 pl-4 text-text-300\">\n<p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\">\u00ab Je suis venu par curiosit\u00e9, sans savoir du tout \u00e0 quoi m&rsquo;attendre. En deux heures, j&rsquo;ai compris que le golf c&rsquo;est bien plus qu&rsquo;un sport \u2014 c&rsquo;est une fa\u00e7on d&rsquo;\u00eatre, un \u00e9quilibre entre concentration et plaisir, dans un cadre magnifique. Je repars avec l&rsquo;envie d&rsquo;en savoir plus ! \u00bb<\/p>\n<p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\"><em>\u2014 Un participant de la section randonn\u00e9e<\/em><\/p>\n<\/blockquote>\n<h2 class=\"text-text-100 mt-3 -mb-1 text-[1.125rem] font-bold\">Un bilan plus que prometteur<\/h2>\n<p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\">La journ\u00e9e a tenu toutes ses promesses. Et la meilleure preuve ? <strong>5 des 11 participants se sont inscrits d\u00e8s le lendemain \u00e0 un stage d&rsquo;initiation<\/strong> pour aller plus loin dans la d\u00e9couverte du golf. Une belle conversion qui laisse pr\u00e9sager de belles retomb\u00e9es pour la section golf de l&rsquo;ATSCAF 63 \u2014 et peut-\u00eatre de nouveaux golfeurs d&rsquo;entreprise en devenir !<\/p>\n<p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\">Merci \u00e0 <strong>Philippe Lequeu<\/strong> pour l&rsquo;accueil et l&rsquo;organisation, \u00e0 <strong>Nicole Audebert-Pichon<\/strong> pour son implication sans faille \u00e0 la t\u00eate de la section golf, et \u00e0 <strong>Serge Paulhan<\/strong> pour la qualit\u00e9 de son enseignement. Merci \u00e9galement au <strong>Golf de Royat Charade<\/strong> pour sa g\u00e9n\u00e9rosit\u00e9 et son hospitalit\u00e9. On esp\u00e8re bien des retomb\u00e9es !<\/p>\n<hr class=\"border-border-200 border-t-0.5 my-3 mx-1.5\" \/>\n<p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\"><em>Ligue Golf d&rsquo;Entreprise \u00b7 Initiation \u00b7 ATSCAF 63 \u00b7 Golf de Royat Charade, Clermont-Ferrand (63) \u00b7 25 avril 2026<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Golf d&rsquo;Entreprise \u00b7 Initiation | Samedi 25 avril 2026 | Golf de Royat Charade \u00b7&#8230;<\/p>\n","protected":false},"author":9,"featured_media":8645,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[144],"tags":[],"class_list":["post-8642","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-developpement"],"_links":{"self":[{"href":"https:\/\/golf-entreprise-ara.org\/wpara\/wp-json\/wp\/v2\/posts\/8642","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/golf-entreprise-ara.org\/wpara\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/golf-entreprise-ara.org\/wpara\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/golf-entreprise-ara.org\/wpara\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/golf-entreprise-ara.org\/wpara\/wp-json\/wp\/v2\/comments?post=8642"}],"version-history":[{"count":2,"href":"https:\/\/golf-entreprise-ara.org\/wpara\/wp-json\/wp\/v2\/posts\/8642\/revisions"}],"predecessor-version":[{"id":8647,"href":"https:\/\/golf-entreprise-ara.org\/wpara\/wp-json\/wp\/v2\/posts\/8642\/revisions\/8647"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/golf-entreprise-ara.org\/wpara\/wp-json\/wp\/v2\/media\/8645"}],"wp:attachment":[{"href":"https:\/\/golf-entreprise-ara.org\/wpara\/wp-json\/wp\/v2\/media?parent=8642"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/golf-entreprise-ara.org\/wpara\/wp-json\/wp\/v2\/categories?post=8642"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/golf-entreprise-ara.org\/wpara\/wp-json\/wp\/v2\/tags?post=8642"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}